{"id":600,"date":"2021-07-19T11:37:42","date_gmt":"2021-07-19T10:37:42","guid":{"rendered":"http:\/\/mimieboutique.com\/?p=600"},"modified":"2021-08-09T12:39:25","modified_gmt":"2021-08-09T11:39:25","slug":"les-lacs-de-plitvice","status":"publish","type":"post","link":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/","title":{"rendered":"Aller aux lacs de Plitvice"},"content":{"rendered":"\r\n<p>La Croatie regorge de magnifiques paysages. Outre sa c\u00f4te et ses \u00eeles spectaculaires, elle compte \u00e9galement plusieurs parcs nationaux notamment, le parc national de Plitvice aux cascades f\u00e9eriques dans un \u00e9crin vallonn\u00e9. Aller aux <a href=\"https:\/\/goo.gl\/maps\/kjkWXwUGHykweTeBA\">lacs de Plitvice<\/a>, c&rsquo;est une mani\u00e8re merveilleuse de d\u00e9couvrir la nature croate.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>Plusieurs sentiers existent autours des lacs de Plitvice. Il y a deux entr\u00e9es principales desquelles on peut donc partir ou arriver selon les sentiers \u00e0 pieds seulement ou \u00e0 pieds et en petit train et bateau. Les plans se trouvent partout sur place donc on peut choisir le sentier le jour J. En revanche, il faut r\u00e9server au moins un jour en avance les billets avec une heure d&rsquo;arriv\u00e9e. Tous les sentiers permettent de voir de magnifiques lacs et cascades donc m\u00eame si vous n&rsquo;avez que quelques heures ou ne pouvez pas beaucoup marcher, vous pourrez en profiter. L&rsquo;endroit est majoritairement plat et j&rsquo;ai crois\u00e9 des personnes \u00e2g\u00e9es et un Monsieur avec des b\u00e9quilles donc c&rsquo;est plut\u00f4t accessible.<\/p>\r\n\r\n\r\n\r\n<p>Les lieux peuvent se visiter en quelques heures ou plusieurs jours. Si les lacs de Plitvice constituent l&rsquo;attraction majeure du parc national, il est aussi possible d&rsquo;effectuer de nombreuses randonn\u00e9es dans la montagne et en bordure de rivi\u00e8re. Avis aux amateurs de randonn\u00e9es qui ont le temps de s&rsquo;\u00e9loigner des sentiers battus, je n&rsquo;en avais pas le temps de mon c\u00f4t\u00e9 car d&rsquo;autres aventures m&rsquo;attendaient.<\/p>\r\n\r\n\r\n\r\n<h2 style=\"text-align: center;\"><strong>Comment aller aux lacs de Plitvice<\/strong><\/h2>\r\n\r\n\r\n\r\n<h3 style=\"text-align: left;\"><strong>En voiture de location<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>J&rsquo;ai lou\u00e9 une voiture de location \u00e0 Zagreb sans carte de cr\u00e9dit. Attention car il faut souvent une carte sp\u00e9ciale et on se retrouve \u00e0 l&rsquo;agence de location de voitures sans pouvoir prendre la voiture m\u00eame si l&rsquo;on a vers\u00e9 une avance).<\/p>\r\n\r\n\r\n\r\n<p>L&rsquo;exp\u00e9rience a \u00e9t\u00e9 formidable en voiture car le GPS m&rsquo;a emmen\u00e9e sur des petites routes traversant la for\u00eat et de jolis petits villages. De plus cela permet une bonne flexibilit\u00e9 de temps avec la possibilit\u00e9 de faire des pauses!<\/p>\r\n\r\n\r\n\r\n<h3><strong>En train<\/strong><\/h3>\r\n<p>Mauvaise nouvelle, ne comptez pas sur les trains en Croatie, il n&rsquo;y en a presque pas! Ils sont surtout utiles pour rallier les capitales voisines<\/p>\r\n\r\n\r\n\r\n<h3><strong>En bus<\/strong><\/h3>\r\n<p>Le bus est la meilleur mani\u00e8re de circuler en transports en communs en Croatie. C&rsquo;est bon march\u00e9 et bien desservi. J&rsquo;ai d&rsquo;ailleurs effectu\u00e9 un trajet de nuit Dubrovnik-Zagreb. Mais cela secoue un peu car ils ont une conduite sportive!<\/p>\r\n\r\n\r\n\r\n<p>Flixbus va \u00e0 Plitvice depuis Zagreb et Zadar notamment.<\/p>\r\n\r\n\r\n\r\n<h3><strong>En avion<\/strong><\/h3>\r\n\r\n\r\n\r\n<h2 style=\"text-align: center;\"><strong>Conseils pratiques Plitvice<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>Les lieux sont assez fr\u00e9quent\u00e9s donc il faut dans l&rsquo;id\u00e9al arriver \u00e0 l&rsquo;ouverture pour \u00e9viter les cars de touristes.<\/p>\r\n\r\n\r\n\r\n<p>Passer une nuit sur place permet de prendre son temps et d&rsquo;arriver \u00e0 l&rsquo;ouverture. Les h\u00f4tels comprennent le petit d\u00e9jeuner.<\/p>\r\n\r\n\r\n\r\n<p>Tous les sentiers sont beaux. De mon c\u00f4t\u00e9 j&rsquo;ai opt\u00e9 pour le H pour partir de l&rsquo;entr\u00e9e 2 o\u00f9 \u00e9tait mon h\u00f4tel. Il est plut\u00f4t rapide avec un bon aper\u00e7u global et on prend le petit train et le bateau!<\/p>\r\n\r\n\r\n\r\n<h3 style=\"text-align: left;\"><strong>O\u00f9 loger aux lacs de Plitvice<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>Plusieurs h\u00f4tels et chambres d&rsquo;h\u00f4tes se trouvent en ces lieux. Il est plus ais\u00e9 de loger \u00e0 proximit\u00e9 des entr\u00e9es mais je pense qu&rsquo;avec une voiture cela doit \u00eatre aussi sympathique de loger en dehors de la zone. En arrivant il y avait plein de restaurants au bord de la route qui font de bonnes grillades. L&rsquo;ambiance semble plus authentique.<\/p>\r\n\r\n\r\n\r\n<p>J&rsquo;ai r\u00e9serv\u00e9 \u00e0 l&rsquo;h\u00f4tel Bellevue qui est \u00e0 c\u00f4t\u00e9 de l&rsquo;entr\u00e9e 2. Tr\u00e8s bien plac\u00e9, pas cher, avec parking,chambre avec balcon et petit-d\u00e9jeuner inclus. J&rsquo;ai m\u00eame pris un caf\u00e9 avant de repartir sur le balcon du restaurant avec une jolie vue.<\/p>\r\n\r\n\r\n\r\n<h2 style=\"text-align: center;\"><strong>Aller plus loin<\/strong><\/h2>\r\n\r\n\r\n\r\n<p>La Croatie c&rsquo;est aussi les magnifiques villes c\u00f4ti\u00e8res de Dubrovnik et <a href=\"https:\/\/mimieboutique.com\/index.php\/2020\/01\/28\/visiter-rovinj\/\">Rovinj<\/a> et la capitale <a href=\"https:\/\/mimieboutique.com\/index.php\/2020\/01\/28\/itineraire-secret-dans-zagreb\/\">Zagreb<\/a>! Voir mes articles!<\/p>\r\n\r\n\r\n\r\n<p>Aux portes de la Croatie on peut facilement rejoindre d&rsquo;autres pays notamment en bus! Voir mes articles sur le <a href=\"https:\/\/mimieboutique.com\/index.php\/2019\/04\/04\/le-montenegro-road-trip-de-podgorica-a-kotor\/\">Mont\u00e9n\u00e9gro<\/a> et sur\u00a0 <a href=\"https:\/\/mimieboutique.com\/index.php\/2020\/01\/10\/itineraire-express-dans-belgrade\/\">Belgrade<\/a>!<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1391\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Autumn-Plitvice-1024x768.jpg\" alt=\"\" data-id=\"1391\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1391\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Autumn-Plitvice-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Autumn-Plitvice-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Autumn-Plitvice-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1392\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lake-1024x768.jpg\" alt=\"\" data-id=\"1392\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1392\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lake-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lake-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lake-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1393\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-1024x768.jpg\" alt=\"\" data-id=\"1393\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1393\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1394\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/magic-moss-forest-1024x768.jpg\" alt=\"\" data-id=\"1394\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1394\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/magic-moss-forest-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/magic-moss-forest-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/magic-moss-forest-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" class=\"wp-image-1395\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-blue-sky-1024x765.jpg\" alt=\"\" data-id=\"1395\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1395\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-blue-sky-1024x765.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-blue-sky-300x224.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-blue-sky-768x574.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1396\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/plitvice-boat-1024x768.jpg\" alt=\"\" data-id=\"1396\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1396\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/plitvice-boat-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/plitvice-boat-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/plitvice-boat-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1397\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-1024x768.jpg\" alt=\"\" data-id=\"1397\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1397\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/Plitvice-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" class=\"wp-image-1398\" src=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/ROOTS-1024x768.jpg\" alt=\"\" data-id=\"1398\" data-link=\"https:\/\/mimieboutique.com\/?attachment_id=1398\" srcset=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/ROOTS-1024x768.jpg 1024w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/ROOTS-300x225.jpg 300w, https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/ROOTS-768x576.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n","protected":false},"excerpt":{"rendered":"<p>La Croatie regorge de magnifiques paysages. Outre sa c\u00f4te et ses \u00eeles spectaculaires, elle compte &hellip; <\/p>\n","protected":false},"author":3,"featured_media":1393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-croatie","latest_post"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aller aux lacs de Plitvice - Mimie boutique<\/title>\n<meta name=\"description\" content=\"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aller aux lacs de Plitvice - Mimie boutique\" \/>\n<meta property=\"og:description\" content=\"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\" \/>\n<meta property=\"og:site_name\" content=\"Mimie boutique\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-19T10:37:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-09T11:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"MM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\"},\"author\":{\"name\":\"MM\",\"@id\":\"https:\/\/mimieboutique.com\/#\/schema\/person\/2980ae90223bc67c8c73ad733287165a\"},\"headline\":\"Aller aux lacs de Plitvice\",\"datePublished\":\"2021-07-19T10:37:42+00:00\",\"dateModified\":\"2021-08-09T11:39:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\/\/mimieboutique.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg\",\"articleSection\":[\"Croatie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\",\"url\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\",\"name\":\"Aller aux lacs de Plitvice - Mimie boutique\",\"isPartOf\":{\"@id\":\"https:\/\/mimieboutique.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg\",\"datePublished\":\"2021-07-19T10:37:42+00:00\",\"dateModified\":\"2021-08-09T11:39:25+00:00\",\"description\":\"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.\",\"breadcrumb\":{\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage\",\"url\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg\",\"contentUrl\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg\",\"width\":4608,\"height\":3456},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/mimieboutique.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aller aux lacs de Plitvice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mimieboutique.com\/#website\",\"url\":\"https:\/\/mimieboutique.com\/\",\"name\":\"Mimie boutique\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/mimieboutique.com\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/mimieboutique.com\/#organization\",\"name\":\"Mimie boutique\",\"url\":\"https:\/\/mimieboutique.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mimieboutique.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2021\/07\/logo-Mimie-bboutique-mois-gras.png\",\"contentUrl\":\"https:\/\/mimieboutique.com\/wp-content\/uploads\/2021\/07\/logo-Mimie-bboutique-mois-gras.png\",\"width\":4000,\"height\":3000,\"caption\":\"Mimie boutique\"},\"image\":{\"@id\":\"https:\/\/mimieboutique.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/mimieboutique.com\/#\/schema\/person\/2980ae90223bc67c8c73ad733287165a\",\"name\":\"MM\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/mimieboutique.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8c0517355ee058ff67715c6bf85d872c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8c0517355ee058ff67715c6bf85d872c?s=96&d=mm&r=g\",\"caption\":\"MM\"},\"url\":\"https:\/\/mimieboutique.com\/index.php\/author\/elise\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aller aux lacs de Plitvice - Mimie boutique","description":"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/","og_locale":"fr_FR","og_type":"article","og_title":"Aller aux lacs de Plitvice - Mimie boutique","og_description":"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.","og_url":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/","og_site_name":"Mimie boutique","article_published_time":"2021-07-19T10:37:42+00:00","article_modified_time":"2021-08-09T11:39:25+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes-1024x768.jpg","type":"image\/jpeg"}],"author":"MM","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"MM","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#article","isPartOf":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/"},"author":{"name":"MM","@id":"https:\/\/mimieboutique.com\/#\/schema\/person\/2980ae90223bc67c8c73ad733287165a"},"headline":"Aller aux lacs de Plitvice","datePublished":"2021-07-19T10:37:42+00:00","dateModified":"2021-08-09T11:39:25+00:00","mainEntityOfPage":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/"},"wordCount":675,"publisher":{"@id":"https:\/\/mimieboutique.com\/#organization"},"image":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage"},"thumbnailUrl":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg","articleSection":["Croatie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/","url":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/","name":"Aller aux lacs de Plitvice - Mimie boutique","isPartOf":{"@id":"https:\/\/mimieboutique.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage"},"image":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage"},"thumbnailUrl":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg","datePublished":"2021-07-19T10:37:42+00:00","dateModified":"2021-08-09T11:39:25+00:00","description":"Aller aux les lacs de Plitvice Que voir? en voiture, train, bus, avion. O\u00f9 loger? Conseils pratiques. Randonn\u00e9es. Parcours.","breadcrumb":{"@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#primaryimage","url":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg","contentUrl":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2020\/01\/lakes.jpg","width":4608,"height":3456},{"@type":"BreadcrumbList","@id":"https:\/\/mimieboutique.com\/index.php\/2021\/07\/19\/les-lacs-de-plitvice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mimieboutique.com\/"},{"@type":"ListItem","position":2,"name":"Aller aux lacs de Plitvice"}]},{"@type":"WebSite","@id":"https:\/\/mimieboutique.com\/#website","url":"https:\/\/mimieboutique.com\/","name":"Mimie boutique","description":"","publisher":{"@id":"https:\/\/mimieboutique.com\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mimieboutique.com\/#organization","name":"Mimie boutique","url":"https:\/\/mimieboutique.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mimieboutique.com\/#\/schema\/logo\/image\/","url":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2021\/07\/logo-Mimie-bboutique-mois-gras.png","contentUrl":"https:\/\/mimieboutique.com\/wp-content\/uploads\/2021\/07\/logo-Mimie-bboutique-mois-gras.png","width":4000,"height":3000,"caption":"Mimie boutique"},"image":{"@id":"https:\/\/mimieboutique.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/mimieboutique.com\/#\/schema\/person\/2980ae90223bc67c8c73ad733287165a","name":"MM","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mimieboutique.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8c0517355ee058ff67715c6bf85d872c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c0517355ee058ff67715c6bf85d872c?s=96&d=mm&r=g","caption":"MM"},"url":"https:\/\/mimieboutique.com\/index.php\/author\/elise\/"}]}},"_links":{"self":[{"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/posts\/600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/comments?post=600"}],"version-history":[{"count":7,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/posts\/600\/revisions"}],"predecessor-version":[{"id":2212,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/posts\/600\/revisions\/2212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/media\/1393"}],"wp:attachment":[{"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/media?parent=600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/categories?post=600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mimieboutique.com\/index.php\/wp-json\/wp\/v2\/tags?post=600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}